{"id":168,"count":16,"description":"Are you looking for Beaux-Arts &amp; Entertainment events that take place in English language? Here is the list. Then join us!","link":"https:\/\/beauxartsentertainment.com\/en\/events-category\/events-in-english-language\/","name":"English language","slug":"events-in-english-language","taxonomy":"mec_category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[:fr]Events in English language - Beaux-Arts &amp; Entertainment[:]<\/title>\n<meta name=\"description\" content=\"[:fr]Here is the list of all Beaux-Arts &amp; Entertainments events (evening classes, workshops,...) provided in English language.[:]\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beauxartsentertainment.com\/en\/events-category\/events-in-english-language\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:fr]Events in English language - Beaux-Arts &amp; Entertainment[:]\" \/>\n<meta property=\"og:description\" content=\"[:fr]Here is the list of all Beaux-Arts &amp; Entertainments events (evening classes, workshops,...) provided in English language.[:]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beauxartsentertainment.com\/en\/events-category\/events-in-english-language\/\" \/>\n<meta property=\"og:site_name\" content=\"Beaux-Arts &amp; Entertainment\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beauxartsentertainment.com\/wp-content\/uploads\/2019\/11\/logo_02_Beaux-ArtsEntertainment_fond.png\" \/>\n\t<meta property=\"og:image:width\" content=\"5000\" \/>\n\t<meta property=\"og:image:height\" content=\"5000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BeauxArtsEnt\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/beauxartsentertainment.com\\\/en\\\/events-category\\\/events-in-english-language\\\/\",\"url\":\"https:\\\/\\\/beauxartsentertainment.com\\\/en\\\/events-category\\\/events-in-english-language\\\/\",\"name\":\"[:fr]Events in English language - Beaux-Arts &amp; Entertainment[:]\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beauxartsentertainment.com\\\/#website\"},\"description\":\"[:fr]Here is the list of all Beaux-Arts & Entertainments events (evening classes, workshops,...) provided in English language.[:]\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beauxartsentertainment.com\\\/en\\\/events-category\\\/events-in-english-language\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beauxartsentertainment.com\\\/en\\\/events-category\\\/events-in-english-language\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"[:fr]Accueil[:]\",\"item\":\"https:\\\/\\\/beauxartsentertainment.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"English language\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beauxartsentertainment.com\\\/#website\",\"url\":\"https:\\\/\\\/beauxartsentertainment.com\\\/\",\"name\":\"Beaux-Arts &amp; Entertainment\",\"description\":\"L\u2019\u00c9cole des M\u00e9tiers du Dessin\",\"publisher\":{\"@id\":\"https:\\\/\\\/beauxartsentertainment.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beauxartsentertainment.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beauxartsentertainment.com\\\/#organization\",\"name\":\"Beaux-Arts & Entertainment\",\"url\":\"https:\\\/\\\/beauxartsentertainment.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/beauxartsentertainment.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beauxartsentertainment.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo_02_Beaux-ArtsEntertainment_fond.png\",\"contentUrl\":\"https:\\\/\\\/beauxartsentertainment.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/logo_02_Beaux-ArtsEntertainment_fond.png\",\"width\":5000,\"height\":5000,\"caption\":\"Beaux-Arts & Entertainment\"},\"image\":{\"@id\":\"https:\\\/\\\/beauxartsentertainment.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BeauxArtsEntertainment\",\"https:\\\/\\\/x.com\\\/BeauxArtsEnt\",\"https:\\\/\\\/www.instagram.com\\\/beauxartsentertainment\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:fr]Events in English language - Beaux-Arts &amp; Entertainment[:]","description":"[:fr]Here is the list of all Beaux-Arts & Entertainments events (evening classes, workshops,...) provided in English language.[:]","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beauxartsentertainment.com\/en\/events-category\/events-in-english-language\/","og_locale":"en_US","og_type":"article","og_title":"[:fr]Events in English language - Beaux-Arts &amp; Entertainment[:]","og_description":"[:fr]Here is the list of all Beaux-Arts & Entertainments events (evening classes, workshops,...) provided in English language.[:]","og_url":"https:\/\/beauxartsentertainment.com\/en\/events-category\/events-in-english-language\/","og_site_name":"Beaux-Arts &amp; Entertainment","og_image":[{"width":5000,"height":5000,"url":"https:\/\/beauxartsentertainment.com\/wp-content\/uploads\/2019\/11\/logo_02_Beaux-ArtsEntertainment_fond.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@BeauxArtsEnt","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/beauxartsentertainment.com\/en\/events-category\/events-in-english-language\/","url":"https:\/\/beauxartsentertainment.com\/en\/events-category\/events-in-english-language\/","name":"[:fr]Events in English language - Beaux-Arts &amp; Entertainment[:]","isPartOf":{"@id":"https:\/\/beauxartsentertainment.com\/#website"},"description":"[:fr]Here is the list of all Beaux-Arts & Entertainments events (evening classes, workshops,...) provided in English language.[:]","breadcrumb":{"@id":"https:\/\/beauxartsentertainment.com\/en\/events-category\/events-in-english-language\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/beauxartsentertainment.com\/en\/events-category\/events-in-english-language\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"[:fr]Accueil[:]","item":"https:\/\/beauxartsentertainment.com\/en\/"},{"@type":"ListItem","position":2,"name":"English language"}]},{"@type":"WebSite","@id":"https:\/\/beauxartsentertainment.com\/#website","url":"https:\/\/beauxartsentertainment.com\/","name":"Beaux-Arts &amp; Entertainment","description":"L\u2019\u00c9cole des M\u00e9tiers du Dessin","publisher":{"@id":"https:\/\/beauxartsentertainment.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beauxartsentertainment.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/beauxartsentertainment.com\/#organization","name":"Beaux-Arts & Entertainment","url":"https:\/\/beauxartsentertainment.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/beauxartsentertainment.com\/#\/schema\/logo\/image\/","url":"https:\/\/beauxartsentertainment.com\/wp-content\/uploads\/2019\/11\/logo_02_Beaux-ArtsEntertainment_fond.png","contentUrl":"https:\/\/beauxartsentertainment.com\/wp-content\/uploads\/2019\/11\/logo_02_Beaux-ArtsEntertainment_fond.png","width":5000,"height":5000,"caption":"Beaux-Arts & Entertainment"},"image":{"@id":"https:\/\/beauxartsentertainment.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BeauxArtsEntertainment","https:\/\/x.com\/BeauxArtsEnt","https:\/\/www.instagram.com\/beauxartsentertainment"]}]}},"_links":{"self":[{"href":"https:\/\/beauxartsentertainment.com\/en\/wp-json\/wp\/v2\/mec_category\/168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beauxartsentertainment.com\/en\/wp-json\/wp\/v2\/mec_category"}],"about":[{"href":"https:\/\/beauxartsentertainment.com\/en\/wp-json\/wp\/v2\/taxonomies\/mec_category"}],"wp:post_type":[{"href":"https:\/\/beauxartsentertainment.com\/en\/wp-json\/wp\/v2\/mec-events?mec_category=168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}